{"id":16610,"date":"2020-09-17T13:12:38","date_gmt":"2020-11-16T15:13:10","guid":{"rendered":"http:\/\/nuovosito.museoomero.it\/?post_type=product&#038;p=16610"},"modified":"2020-11-18T17:04:30","modified_gmt":"2020-11-18T16:04:30","slug":"katalogo-toccare-gli-angeli-inediti-marmi-di-gioacchino-varle-al-museo-omero","status":"publish","type":"product","link":"https:\/\/museoomero.it\/eo\/prodotto\/katalogo-toccare-gli-angeli-inediti-marmi-di-gioacchino-varle-al-museo-omero\/","title":{"rendered":"Katalogo Toccare gli angeli \u2013 Inediti marmi di Gioacchino Varl\u00e8 al Museo Omero"},"content":{"rendered":"<p>La katalogo, realigita okaze de la ekspozicio &#8220;Toccare gli angeli&#8221; (Pripalpi an\u011delojn), 3a de Decembro 2009 \u2013 20a de Junio 2010, pere de kolekto da bildoj kaj tekstoj, redonas la artajn spertojn de Varl\u00e8 en la urbo Ankono, ekde la ekspoziciataj verkoj. Zorge de Massimo Di Matteo, Nadia Falaschini, Diego Masala kun kontribua\u0135oj de la Prezidanto de Muzeo Homero, Roberto Farroni, de la \u0108efepiskopo de la Arkidiocezo Ankono-Osimo, Monsinjoro Edoardo Menichelli, kaj de arkitekto Massimo Di Matteo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Speco: Katalogo.<br \/>\nPa\u011doj: 36.<br \/>\nEldonis: Muzeo Homero.<\/p>\n","protected":false},"featured_media":10942,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[15],"product_tag":[],"class_list":{"0":"post-16610","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-cataloghi-saggi-dispense","8":"first","9":"instock","10":"purchasable","11":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Katalogo Toccare gli angeli \u2013 Inediti marmi di Gioacchino Varl\u00e8 al Museo Omero - Museo Omero<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/museoomero.it\/eo\/prodotto\/katalogo-toccare-gli-angeli-inediti-marmi-di-gioacchino-varle-al-museo-omero\/\" \/>\n<meta property=\"og:locale\" content=\"eo_EO\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Katalogo Toccare gli angeli \u2013 Inediti marmi di Gioacchino Varl\u00e8 al Museo Omero - Museo Omero\" \/>\n<meta property=\"og:description\" content=\"Speco: Katalogo. Pa\u011doj: 36. Eldonis: Muzeo Homero.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/museoomero.it\/eo\/prodotto\/katalogo-toccare-gli-angeli-inediti-marmi-di-gioacchino-varle-al-museo-omero\/\" \/>\n<meta property=\"og:site_name\" content=\"Museo Omero\" \/>\n<meta property=\"article:modified_time\" content=\"2020-11-18T16:04:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/museoomero.it\/wp-content\/uploads\/2020\/09\/pubblicazioni-varl\u00e8-2009.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"1133\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/museoomero.it\\\/eo\\\/prodotto\\\/katalogo-toccare-gli-angeli-inediti-marmi-di-gioacchino-varle-al-museo-omero\\\/\",\"url\":\"https:\\\/\\\/museoomero.it\\\/eo\\\/prodotto\\\/katalogo-toccare-gli-angeli-inediti-marmi-di-gioacchino-varle-al-museo-omero\\\/\",\"name\":\"Katalogo Toccare gli angeli \u2013 Inediti marmi di Gioacchino Varl\u00e8 al Museo Omero - Museo Omero\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/museoomero.it\\\/eo\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/museoomero.it\\\/eo\\\/prodotto\\\/katalogo-toccare-gli-angeli-inediti-marmi-di-gioacchino-varle-al-museo-omero\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/museoomero.it\\\/eo\\\/prodotto\\\/katalogo-toccare-gli-angeli-inediti-marmi-di-gioacchino-varle-al-museo-omero\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/museoomero.it\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/pubblicazioni-varl\u00e8-2009.jpg\",\"datePublished\":\"2020-11-16T15:13:10+00:00\",\"dateModified\":\"2020-11-18T16:04:30+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/museoomero.it\\\/eo\\\/prodotto\\\/katalogo-toccare-gli-angeli-inediti-marmi-di-gioacchino-varle-al-museo-omero\\\/#breadcrumb\"},\"inLanguage\":\"eo-UY\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/museoomero.it\\\/eo\\\/prodotto\\\/katalogo-toccare-gli-angeli-inediti-marmi-di-gioacchino-varle-al-museo-omero\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"eo-UY\",\"@id\":\"https:\\\/\\\/museoomero.it\\\/eo\\\/prodotto\\\/katalogo-toccare-gli-angeli-inediti-marmi-di-gioacchino-varle-al-museo-omero\\\/#primaryimage\",\"url\":\"https:\\\/\\\/museoomero.it\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/pubblicazioni-varl\u00e8-2009.jpg\",\"contentUrl\":\"https:\\\/\\\/museoomero.it\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/pubblicazioni-varl\u00e8-2009.jpg\",\"width\":1200,\"height\":1133,\"caption\":\"Catalogo Toccare gli angeli - Inediti marmi di Gioacchino Varl\u00e8 al Museo Omero\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/museoomero.it\\\/eo\\\/prodotto\\\/katalogo-toccare-gli-angeli-inediti-marmi-di-gioacchino-varle-al-museo-omero\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"A\u0109etejo\",\"item\":\"https:\\\/\\\/museoomero.it\\\/eo\\\/acetejo\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Katalogo Toccare gli angeli \u2013 Inediti marmi di Gioacchino Varl\u00e8 al Museo Omero\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/museoomero.it\\\/eo\\\/#website\",\"url\":\"https:\\\/\\\/museoomero.it\\\/eo\\\/\",\"name\":\"Museo Omero\",\"description\":\"Museo Tattile Statale\",\"publisher\":{\"@id\":\"https:\\\/\\\/museoomero.it\\\/eo\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/museoomero.it\\\/eo\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"eo-UY\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/museoomero.it\\\/eo\\\/#organization\",\"name\":\"Museo Omero\",\"url\":\"https:\\\/\\\/museoomero.it\\\/eo\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"eo-UY\",\"@id\":\"https:\\\/\\\/museoomero.it\\\/eo\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/museoomero.it\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/logo_museoomero_nomibact.png\",\"contentUrl\":\"https:\\\/\\\/museoomero.it\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/logo_museoomero_nomibact.png\",\"width\":400,\"height\":127,\"caption\":\"Museo Omero\"},\"image\":{\"@id\":\"https:\\\/\\\/museoomero.it\\\/eo\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Katalogo Toccare gli angeli \u2013 Inediti marmi di Gioacchino Varl\u00e8 al Museo Omero - Museo Omero","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/museoomero.it\/eo\/prodotto\/katalogo-toccare-gli-angeli-inediti-marmi-di-gioacchino-varle-al-museo-omero\/","og_locale":"eo_EO","og_type":"article","og_title":"Katalogo Toccare gli angeli \u2013 Inediti marmi di Gioacchino Varl\u00e8 al Museo Omero - Museo Omero","og_description":"Speco: Katalogo. Pa\u011doj: 36. Eldonis: Muzeo Homero.","og_url":"https:\/\/museoomero.it\/eo\/prodotto\/katalogo-toccare-gli-angeli-inediti-marmi-di-gioacchino-varle-al-museo-omero\/","og_site_name":"Museo Omero","article_modified_time":"2020-11-18T16:04:30+00:00","og_image":[{"width":1200,"height":1133,"url":"https:\/\/museoomero.it\/wp-content\/uploads\/2020\/09\/pubblicazioni-varl\u00e8-2009.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/museoomero.it\/eo\/prodotto\/katalogo-toccare-gli-angeli-inediti-marmi-di-gioacchino-varle-al-museo-omero\/","url":"https:\/\/museoomero.it\/eo\/prodotto\/katalogo-toccare-gli-angeli-inediti-marmi-di-gioacchino-varle-al-museo-omero\/","name":"Katalogo Toccare gli angeli \u2013 Inediti marmi di Gioacchino Varl\u00e8 al Museo Omero - Museo Omero","isPartOf":{"@id":"https:\/\/museoomero.it\/eo\/#website"},"primaryImageOfPage":{"@id":"https:\/\/museoomero.it\/eo\/prodotto\/katalogo-toccare-gli-angeli-inediti-marmi-di-gioacchino-varle-al-museo-omero\/#primaryimage"},"image":{"@id":"https:\/\/museoomero.it\/eo\/prodotto\/katalogo-toccare-gli-angeli-inediti-marmi-di-gioacchino-varle-al-museo-omero\/#primaryimage"},"thumbnailUrl":"https:\/\/museoomero.it\/wp-content\/uploads\/2020\/09\/pubblicazioni-varl\u00e8-2009.jpg","datePublished":"2020-11-16T15:13:10+00:00","dateModified":"2020-11-18T16:04:30+00:00","breadcrumb":{"@id":"https:\/\/museoomero.it\/eo\/prodotto\/katalogo-toccare-gli-angeli-inediti-marmi-di-gioacchino-varle-al-museo-omero\/#breadcrumb"},"inLanguage":"eo-UY","potentialAction":[{"@type":"ReadAction","target":["https:\/\/museoomero.it\/eo\/prodotto\/katalogo-toccare-gli-angeli-inediti-marmi-di-gioacchino-varle-al-museo-omero\/"]}]},{"@type":"ImageObject","inLanguage":"eo-UY","@id":"https:\/\/museoomero.it\/eo\/prodotto\/katalogo-toccare-gli-angeli-inediti-marmi-di-gioacchino-varle-al-museo-omero\/#primaryimage","url":"https:\/\/museoomero.it\/wp-content\/uploads\/2020\/09\/pubblicazioni-varl\u00e8-2009.jpg","contentUrl":"https:\/\/museoomero.it\/wp-content\/uploads\/2020\/09\/pubblicazioni-varl\u00e8-2009.jpg","width":1200,"height":1133,"caption":"Catalogo Toccare gli angeli - Inediti marmi di Gioacchino Varl\u00e8 al Museo Omero"},{"@type":"BreadcrumbList","@id":"https:\/\/museoomero.it\/eo\/prodotto\/katalogo-toccare-gli-angeli-inediti-marmi-di-gioacchino-varle-al-museo-omero\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"A\u0109etejo","item":"https:\/\/museoomero.it\/eo\/acetejo\/"},{"@type":"ListItem","position":2,"name":"Katalogo Toccare gli angeli \u2013 Inediti marmi di Gioacchino Varl\u00e8 al Museo Omero"}]},{"@type":"WebSite","@id":"https:\/\/museoomero.it\/eo\/#website","url":"https:\/\/museoomero.it\/eo\/","name":"Museo Omero","description":"Museo Tattile Statale","publisher":{"@id":"https:\/\/museoomero.it\/eo\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/museoomero.it\/eo\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"eo-UY"},{"@type":"Organization","@id":"https:\/\/museoomero.it\/eo\/#organization","name":"Museo Omero","url":"https:\/\/museoomero.it\/eo\/","logo":{"@type":"ImageObject","inLanguage":"eo-UY","@id":"https:\/\/museoomero.it\/eo\/#\/schema\/logo\/image\/","url":"https:\/\/museoomero.it\/wp-content\/uploads\/2019\/12\/logo_museoomero_nomibact.png","contentUrl":"https:\/\/museoomero.it\/wp-content\/uploads\/2019\/12\/logo_museoomero_nomibact.png","width":400,"height":127,"caption":"Museo Omero"},"image":{"@id":"https:\/\/museoomero.it\/eo\/#\/schema\/logo\/image\/"}}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/museoomero.it\/eo\/wp-json\/wp\/v2\/product\/16610","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/museoomero.it\/eo\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/museoomero.it\/eo\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/museoomero.it\/eo\/wp-json\/wp\/v2\/media\/10942"}],"wp:attachment":[{"href":"https:\/\/museoomero.it\/eo\/wp-json\/wp\/v2\/media?parent=16610"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/museoomero.it\/eo\/wp-json\/wp\/v2\/product_brand?post=16610"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/museoomero.it\/eo\/wp-json\/wp\/v2\/product_cat?post=16610"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/museoomero.it\/eo\/wp-json\/wp\/v2\/product_tag?post=16610"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}